{"id":1631,"date":"2020-09-25T12:16:17","date_gmt":"2020-09-25T10:16:17","guid":{"rendered":"https:\/\/agronet.cat\/?post_type=product&#038;p=1631"},"modified":"2020-09-25T12:18:49","modified_gmt":"2020-09-25T10:18:49","slug":"sonda-temperatura-per-ph-metre-860-810","status":"publish","type":"product","link":"https:\/\/old.agronet.cat\/es\/botiga\/recanvis-i-subministres-per-a-medicio\/sonda-temperatura-per-ph-metre-860-810\/","title":{"rendered":"SONDA TEMPERATURA PARA pH METRO 860-810"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"translation-block\">Sonda de penetraci\u00f3n de termistor de pH para el medidor de pH y Temperature-ra 8100 Plus - 170-100Sonda de recambio para kit de pH 8100 Plus. <br>\nTiempo de respuesta inferior a 4 segundos.<\/p>","protected":false},"featured_media":1632,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[42],"product_tag":[],"class_list":["post-1631","product","type-product","status-publish","has-post-thumbnail","product_cat-recanvis-i-subministres-per-a-medicio","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media\/1632"}],"wp:attachment":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_brand?post=1631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_cat?post=1631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_tag?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}