{"id":2251,"date":"2020-09-29T13:33:22","date_gmt":"2020-09-29T11:33:22","guid":{"rendered":"https:\/\/agronet.cat\/?post_type=product&#038;p=2251"},"modified":"2020-10-22T12:05:46","modified_gmt":"2020-10-22T10:05:46","slug":"raspall-de-mar-dur-ref-38853","status":"publish","type":"product","link":"https:\/\/old.agronet.cat\/es\/botiga\/accessoris-de-neteja\/raspall-de-mar-dur-ref-38853\/","title":{"rendered":"RASPALL DE M\u00c1 DUR Ref. 38853"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Excelente para limpiar dep\u00f3sitos en forma de caja, ya que los cepillos angulares permiten llegar a los rincones.<\/p>\n<p><strong>Tama\u00f1o: <\/strong>\u00d8110 mm<br \/>\n<strong>Material:<\/strong> Polipropileno<\/p>","protected":false},"featured_media":2258,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":["post-2251","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoris-de-neteja","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media\/2258"}],"wp:attachment":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_brand?post=2251"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_cat?post=2251"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_tag?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}