{"id":3519,"date":"2020-10-05T13:05:28","date_gmt":"2020-10-05T11:05:28","guid":{"rendered":"https:\/\/agronet.cat\/?post_type=product&#038;p=3519"},"modified":"2020-10-05T13:08:58","modified_gmt":"2020-10-05T11:08:58","slug":"vestit-daigua-ref-tpv13v","status":"publish","type":"product","link":"https:\/\/old.agronet.cat\/es\/botiga\/equipament-personal\/vestit-daigua-ref-tpv13v\/","title":{"rendered":"TRAJE DE AGUA ref. TPV13V"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p class=\"translation-block\">Ropa de agua impermeable completa tipo ingeniero, compuesto por una chaqueta totalmente impermeable y un pantal\u00f3n de agua resistentes y flexibles. <br>\nResistente al desgarro, con costuras cosidas y termo-selladas. <br>\nCon ventilaci\u00f3n dorsal.<\/p>\n<p><strong>Composici\u00f3n:<\/strong> PVC<\/p>","protected":false},"featured_media":3532,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":["post-3519","product","type-product","status-publish","has-post-thumbnail","product_cat-equipament-personal","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product\/3519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media\/3532"}],"wp:attachment":[{"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/media?parent=3519"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_brand?post=3519"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_cat?post=3519"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/old.agronet.cat\/es\/wp-json\/wp\/v2\/product_tag?post=3519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}